{"id":11222,"date":"2022-12-16T04:10:38","date_gmt":"2022-12-16T04:10:38","guid":{"rendered":"https:\/\/fertycare.com\/?page_id=11222"},"modified":"2025-03-14T03:54:10","modified_gmt":"2025-03-14T03:54:10","slug":"blog","status":"publish","type":"page","link":"https:\/\/fertycare.com\/en\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11222\" class=\"elementor elementor-11222\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb14b54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb14b54\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a082ea5\" data-id=\"a082ea5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32fb868 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"32fb868\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Blog<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f18c7e2 elementor-align-center elementor-invisible elementor-widget elementor-widget-post-info\" data-id=\"f18c7e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-c9b9cd1 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/fertycare.com\/en\/author\/poncho\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-verified\" data-md-icon=\"verified\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tFertyCare Group\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-478da45f elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"478da45f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b951894\" data-id=\"5b951894\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf33c16 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"cf33c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14249 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fertycare.com\/en\/hiv-parenting-surrogacy\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1919\" height=\"1281\" src=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op.jpg\" class=\"attachment-full size-full wp-image-14342\" alt=\"Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion\" srcset=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op.jpg 1919w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op-300x200.jpg 300w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op-1024x684.jpg 1024w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op-768x513.jpg 768w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op-1536x1025.jpg 1536w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/05\/10-Pueden-las-personas-con-VIH-ser-padres-mediante-subrogacion-1920-op-18x12.jpg 18w\" sizes=\"(max-width: 1919px) 100vw, 1919px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fertycare.com\/en\/hiv-parenting-surrogacy\/\" >\n\t\t\t\t\u00bfPueden las personas con VIH ser padres mediante subrogaci\u00f3n? La respuesta es s\u00ed\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00bfC\u00f3mo el lavado de esperma y los avances m\u00e9dicos hacen posible la paternidad segura para la comunidad LGBT+ con VIH? Para las parejas y personas de la comunidad LGBTQ+ con VIH, el sue\u00f1o de ser padres puede parecer lejano debido a mitos y desinformaci\u00f3n. Sin embargo, gracias a t\u00e9cnicas innovadoras<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fertycare.com\/en\/hiv-parenting-surrogacy\/\" aria-label=\"Read more about \u00bfPueden las personas con VIH ser padres mediante subrogaci\u00f3n? La respuesta es s\u00ed\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13858 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fertycare.com\/en\/how-to-choose-the-right-fertility-clinic-a-guide-for-same-sex-couples\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1281\" src=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES.jpg\" class=\"attachment-full size-full wp-image-13383\" alt=\"\" srcset=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES.jpg 1920w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES-300x200.jpg 300w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES-1024x683.jpg 1024w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES-768x512.jpg 768w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES-1536x1025.jpg 1536w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/8-COMO-ELEGIR-LA-CLINICA-DE-FERTILIDAD-ADECUADA_-UNA-GUIA-PARA-PAREJAS-HOMOPARENTALES-18x12.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fertycare.com\/en\/how-to-choose-the-right-fertility-clinic-a-guide-for-same-sex-couples\/\" >\n\t\t\t\tC\u00f3mo eligir la cl\u00ednica de fertilidad adecuada: Una gu\u00eda para parejas homoparentales\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La decisi\u00f3n de formar una familia es un paso significativo y emocionante, y para las parejas homoparentales, la elecci\u00f3n de una cl\u00ednica de fertilidad es esencial para llevar a cabo este sue\u00f1o. Aqu\u00ed te ofrecemos 10 consejos y factores a considerar al seleccionar la cl\u00ednica de fertilidad que mejor se<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fertycare.com\/en\/how-to-choose-the-right-fertility-clinic-a-guide-for-same-sex-couples\/\" aria-label=\"Read more about C\u00f3mo eligir la cl\u00ednica de fertilidad adecuada: Una gu\u00eda para parejas homoparentales\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13842 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fertycare.com\/en\/assisted-reproduction-a-milestone-in-human-rights-and-diversity-in-the-lgbt-community\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1076\" src=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ.jpg\" class=\"attachment-full size-full wp-image-13382\" alt=\"\" srcset=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ.jpg 1920w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ-300x168.jpg 300w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ-1024x574.jpg 1024w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ-768x430.jpg 768w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ-1536x861.jpg 1536w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/7.-REPRODUCCION-ASISTIDA_-HITO-EN-LOS-DERECHOS-HUMANOS-Y-LA-DIVERSIDAD-EN-LA-COMUNIDAD-LGBTTTIQ-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fertycare.com\/en\/assisted-reproduction-a-milestone-in-human-rights-and-diversity-in-the-lgbt-community\/\" >\n\t\t\t\tReproducci\u00f3n Asistida: Hito en los derechos humanos y la diversidad en la comunidad LGBTTTIQ+\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Reproducci\u00f3n Asistida: Hito en los derechos humanos y la diversidad en la comunidad LGBTTTIQ+ \u201cLos derechos de los homosexuales son derechos humanos y los derechos humanos son derechos de homosexuales\u201d. &nbsp; Hillary Clinton, ex candidata a la presidencia de Estados Unidos.\u00a0 La reproducci\u00f3n asistida ha emergido como una herramienta vital<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fertycare.com\/en\/assisted-reproduction-a-milestone-in-human-rights-and-diversity-in-the-lgbt-community\/\" aria-label=\"Read more about Reproducci\u00f3n Asistida: Hito en los derechos humanos y la diversidad en la comunidad LGBTTTIQ+\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13412 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fertycare.com\/en\/letter-3-when-we-said-yes\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1828\" src=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-scaled.webp\" class=\"attachment-full size-full wp-image-13413\" alt=\"Carta #3 Mateo\" srcset=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-scaled.webp 2560w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-300x214.webp 300w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-1024x731.webp 1024w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-768x549.webp 768w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-1536x1097.webp 1536w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-2048x1463.webp 2048w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta3-18x12.webp 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fertycare.com\/en\/letter-3-when-we-said-yes\/\" >\n\t\t\t\tCarta #3: Cuando Dijimos \u201cS\u00ed\u201d\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Mateo, esta es nuestra historia\u2026 Un mensaje de texto que lo cambi\u00f3 todo &#x1f4c5; 16 de febrero de 2021 :: Mensaje de texto de Robert ::Cuidado de la fertilidad.+52 4492 27 &#8220;Ella es coordinadora de pacientes o algo as\u00ed.&#8221; Llam\u00e9 al d\u00eda siguiente y la voz al otro lado de<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fertycare.com\/en\/letter-3-when-we-said-yes\/\" aria-label=\"Read more about Carta #3: Cuando Dijimos \u201cS\u00ed\u201d\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13409 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fertycare.com\/en\/letter-2-three-agencies-after-spanish\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1821\" height=\"2276\" src=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2.webp\" class=\"attachment-full size-full wp-image-13410\" alt=\"Carta #2 Mateo\" srcset=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2.webp 1821w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2-240x300.webp 240w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2-819x1024.webp 819w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2-768x960.webp 768w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2-1229x1536.webp 1229w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2-1639x2048.webp 1639w, https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/carta2-10x12.webp 10w\" sizes=\"(max-width: 1821px) 100vw, 1821px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fertycare.com\/en\/letter-2-three-agencies-after-spanish\/\" >\n\t\t\t\tCarta #2: Tres Agencias Despu\u00e9s (Espa\u00f1ol)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>En 2020, la pandemia de coronavirus oblig\u00f3 al mundo a detenerse. Durante meses de aislamiento, mi esposo, Papi Mart\u00edn, y yo tuvimos el tiempo para reflexionar sobre la vida y la familia que dese\u00e1bamos formar. Siempre hab\u00edamos hablado de la posibilidad de ser padres, y sin distracciones, finalmente comenzamos a<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fertycare.com\/en\/letter-2-three-agencies-after-spanish\/\" aria-label=\"Read more about Carta #2: Tres Agencias Despu\u00e9s (Espa\u00f1ol)\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13407 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/fertycare.com\/en\/when-an-egg-donor-is-needed-2\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1050\" src=\"https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480.jpg\" class=\"attachment-full size-full wp-image-11786\" alt=\"\" srcset=\"https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480.jpg 1920w, https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480-300x164.jpg 300w, https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480-1024x560.jpg 1024w, https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480-768x420.jpg 768w, https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480-1536x840.jpg 1536w, https:\/\/fertycare.com\/wp-content\/uploads\/2024\/03\/mama-fertycare_1-e1711150852480-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/fertycare.com\/en\/when-an-egg-donor-is-needed-2\/\" >\n\t\t\t\t\u00bfCu\u00e1ndo se Necesita una Donante de \u00d3vulos?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Las donantes de \u00f3vulos son mujeres j\u00f3venes y sanas que pueden ayudar a mujeres solteras, hombres solteros, parejas heterosexuales y parejas homoparentales a cumplir su sue\u00f1o de ser padres. Si eres un hombre soltero o una pareja gay, necesitar\u00e1s recurrir a una donante de \u00f3vulos y a una gestante sustituta<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/fertycare.com\/en\/when-an-egg-donor-is-needed-2\/\" aria-label=\"Read more about \u00bfCu\u00e1ndo se Necesita una Donante de \u00d3vulos?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"3\" data-next-page=\"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">&laquo; Anterior<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222\/page\/3\/\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222\/page\/2\/\">Siguiente &raquo;<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":13168,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"class_list":["post-11222","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestro Blog | FertyCare<\/title>\n<meta name=\"description\" content=\"Art\u00edculos de inter\u00e9s enfocados a temas de fertilidad y subrogaci\u00f3n. Bienvenido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fertycare.com\/en\/blog\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestro Blog | FertyCare\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculos de inter\u00e9s enfocados a temas de fertilidad y subrogaci\u00f3n. Bienvenido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fertycare.com\/en\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"FertyCare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fertycare\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-14T03:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/Mural-2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2388\" \/>\n\t<meta property=\"og:image:height\" content=\"1416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/\",\"url\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/\",\"name\":\"Nuestro Blog | FertyCare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fertycare.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fertycare.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mural-2-1.png\",\"datePublished\":\"2022-12-16T04:10:38+00:00\",\"dateModified\":\"2025-03-14T03:54:10+00:00\",\"description\":\"Art\u00edculos de inter\u00e9s enfocados a temas de fertilidad y subrogaci\u00f3n. Bienvenido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fertycare.com\\\/blog\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fertycare.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mural-2-1.png\",\"contentUrl\":\"https:\\\/\\\/fertycare.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mural-2-1.png\",\"width\":2388,\"height\":1416},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fertycare.com\\\/blog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fertycare.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fertycare.com\\\/#website\",\"url\":\"https:\\\/\\\/fertycare.com\\\/\",\"name\":\"FertyCare\",\"description\":\"Fertilidad y Servicios M\u00e9dicos de Calidad Accesibles\",\"publisher\":{\"@id\":\"https:\\\/\\\/fertycare.com\\\/#organization\"},\"alternateName\":\"FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fertycare.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fertycare.com\\\/#organization\",\"name\":\"FertyCare | Especialistas en Fertilidad\",\"alternateName\":\"FC\",\"url\":\"https:\\\/\\\/fertycare.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fertycare.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fertycare.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-03.svg\",\"contentUrl\":\"https:\\\/\\\/fertycare.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo-03.svg\",\"width\":459,\"height\":179,\"caption\":\"FertyCare | Especialistas en Fertilidad\"},\"image\":{\"@id\":\"https:\\\/\\\/fertycare.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fertycare\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fertycare\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCSAMhfofTi2TsJJ9pJC2H5Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our Blog | FertyCare","description":"Articles of interest focused on fertility and surrogacy issues. Welcome.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fertycare.com\/en\/blog\/","og_locale":"en_US","og_type":"article","og_title":"Nuestro Blog | FertyCare","og_description":"Art\u00edculos de inter\u00e9s enfocados a temas de fertilidad y subrogaci\u00f3n. Bienvenido.","og_url":"https:\/\/fertycare.com\/en\/blog\/","og_site_name":"FertyCare","article_publisher":"https:\/\/www.facebook.com\/fertycare\/","article_modified_time":"2025-03-14T03:54:10+00:00","og_image":[{"width":2388,"height":1416,"url":"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/Mural-2-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fertycare.com\/blog\/","url":"https:\/\/fertycare.com\/blog\/","name":"Our Blog | FertyCare","isPartOf":{"@id":"https:\/\/fertycare.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fertycare.com\/blog\/#primaryimage"},"image":{"@id":"https:\/\/fertycare.com\/blog\/#primaryimage"},"thumbnailUrl":"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/Mural-2-1.png","datePublished":"2022-12-16T04:10:38+00:00","dateModified":"2025-03-14T03:54:10+00:00","description":"Articles of interest focused on fertility and surrogacy issues. Welcome.","breadcrumb":{"@id":"https:\/\/fertycare.com\/blog\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fertycare.com\/blog\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fertycare.com\/blog\/#primaryimage","url":"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/Mural-2-1.png","contentUrl":"https:\/\/fertycare.com\/wp-content\/uploads\/2025\/02\/Mural-2-1.png","width":2388,"height":1416},{"@type":"BreadcrumbList","@id":"https:\/\/fertycare.com\/blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fertycare.com\/"},{"@type":"ListItem","position":2,"name":"Blog"}]},{"@type":"WebSite","@id":"https:\/\/fertycare.com\/#website","url":"https:\/\/fertycare.com\/","name":"FertyCare","description":"Affordable Fertility and Quality Medical Services","publisher":{"@id":"https:\/\/fertycare.com\/#organization"},"alternateName":"FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fertycare.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fertycare.com\/#organization","name":"FertyCare | Fertility Specialists","alternateName":"FC","url":"https:\/\/fertycare.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fertycare.com\/#\/schema\/logo\/image\/","url":"https:\/\/fertycare.com\/wp-content\/uploads\/2020\/10\/logo-03.svg","contentUrl":"https:\/\/fertycare.com\/wp-content\/uploads\/2020\/10\/logo-03.svg","width":459,"height":179,"caption":"FertyCare | Especialistas en Fertilidad"},"image":{"@id":"https:\/\/fertycare.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fertycare\/","https:\/\/www.instagram.com\/fertycare\/","https:\/\/www.youtube.com\/channel\/UCSAMhfofTi2TsJJ9pJC2H5Q"]}]}},"_links":{"self":[{"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/comments?post=11222"}],"version-history":[{"count":9,"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222\/revisions"}],"predecessor-version":[{"id":13949,"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/pages\/11222\/revisions\/13949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/media\/13168"}],"wp:attachment":[{"href":"https:\/\/fertycare.com\/en\/wp-json\/wp\/v2\/media?parent=11222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}